{"id":104049,"date":"2026-09-01T09:10:21","date_gmt":"2026-09-01T07:10:21","guid":{"rendered":"https:\/\/hantom.ch\/product\/r0302005-systeme-detancheite-okt-autogonflable-coussin-detancheite-okt-200-adapte-pour-tube-en-pe-150-8\/"},"modified":"2026-06-23T13:21:17","modified_gmt":"2026-06-23T11:21:17","slug":"r0302005-systeme-detancheite-okt-autogonflable-coussin-detancheite-okt-200-adapte-pour-tube-en-pe-150-8","status":"publish","type":"product","link":"https:\/\/hantom.ch\/fr\/produit\/r0302005-systeme-detancheite-okt-autogonflable-coussin-detancheite-okt-200-adapte-pour-tube-en-pe-150-8\/","title":{"rendered":"R0302005 &#8211; Syst\u00e8me d&apos;\u00e9tanch\u00e9it\u00e9 OKT, autogonflable Coussin d&apos;\u00e9tanch\u00e9it\u00e9 OKT 200, adapt\u00e9 pour tube en PE 150 (8)"},"content":{"rendered":"<p>Pour l&apos;\u00e9tanch\u00e9it\u00e9 des c\u00e2bles dans des tubes en PE,<br \/>des carottages ou des tubes de cuvelage.<\/p>\n<p>&#8211; Tube\/carottage 150-165 mm<br \/>&#8211; 1 c\u00e2ble 19-135 mm<\/p>\n<p>y compris 1 x lubrifiant<\/p>\n<p>Paquet de 8 pi\u00e8ces<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour l&apos;\u00e9tanch\u00e9it\u00e9 des c\u00e2bles dans des tubes en PE,des carottages ou des tubes de cuvelage. &#8211; Tube\/carottage 150-165 mm&#8211; 1 c\u00e2ble 19-135 mm y compris 1 x lubrifiant Paquet de 8 pi\u00e8ces<\/p>\n","protected":false},"featured_media":83590,"template":"","meta":[],"product_brand":[],"product_cat":[1489,1478,1466],"product_tag":[],"class_list":["post-104049","product","type-product","status-publish","has-post-thumbnail","product_cat-r0302-fr","product_cat-r03-fr","product_cat-r-fr","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/hantom.ch\/fr\/wp-json\/wp\/v2\/product\/104049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hantom.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/hantom.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hantom.ch\/fr\/wp-json\/wp\/v2\/media\/83590"}],"wp:attachment":[{"href":"https:\/\/hantom.ch\/fr\/wp-json\/wp\/v2\/media?parent=104049"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/hantom.ch\/fr\/wp-json\/wp\/v2\/product_brand?post=104049"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hantom.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=104049"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hantom.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=104049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}